{"id":25219,"date":"2025-03-08T21:22:01","date_gmt":"2025-03-09T02:22:01","guid":{"rendered":"https:\/\/purealpacastores.com\/peru\/?post_type=product&#038;p=25219"},"modified":"2026-05-04T08:12:29","modified_gmt":"2026-05-04T13:12:29","slug":"chompa-alvaro","status":"publish","type":"product","link":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/","title":{"rendered":"Su\u00e9ter Alvaro Beige"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":26060,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[520,523],"product_tag":[],"class_list":{"0":"post-25219","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-color-of-the-andes","7":"product_cat-hombre","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"product-type-variable"},"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":true,"inbound_stock":null,"stock_on_hold":0,"sold_today":0,"sales_last_days":0,"reserved_stock":null,"customer_returns":null,"warehouse_damage":null,"lost_in_post":null,"other_logs":null,"out_stock_days":0,"lost_sales":0,"has_location":false,"update_date":"2026-05-13T00:09:50","atum_locations":[],"atum_stock_status":"outofstock","restock_status":false,"low_stock_amount":"","sales_update_date":"2026-05-13T00:09:50","calc_backorders":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Su\u00e9ter Alvaro Beige - Pure Alpaca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Su\u00e9ter Alvaro Beige - Pure Alpaca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/\" \/>\n<meta property=\"og:site_name\" content=\"Pure Alpaca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/purealpacaofficial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T13:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2025\/04\/Chompa-Alvarao_Beige_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1004\" \/>\n\t<meta property=\"og:image:height\" content=\"1504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/\",\"url\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/\",\"name\":\"Su\u00e9ter Alvaro Beige - Pure Alpaca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Chompa-Alvarao_Beige_1.jpg\",\"datePublished\":\"2025-03-09T02:22:01+00:00\",\"dateModified\":\"2026-05-04T13:12:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Chompa-Alvarao_Beige_1.jpg\",\"contentUrl\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Chompa-Alvarao_Beige_1.jpg\",\"width\":1004,\"height\":1504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/producto\\\/chompa-alvaro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Su\u00e9ter Alvaro Beige\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/#website\",\"url\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/\",\"name\":\"Pure Alpaca\",\"description\":\"Boutique de Prendas de Alpaca\",\"publisher\":{\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/#organization\",\"name\":\"Pure Alpaca\",\"url\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-2da-version-1.png\",\"contentUrl\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-2da-version-1.png\",\"width\":300,\"height\":200,\"caption\":\"Pure Alpaca\"},\"image\":{\"@id\":\"https:\\\/\\\/purealpacastores.com\\\/peru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/purealpacaofficial\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGZZKwsBB5LtQ_jlpO0AdHA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Su\u00e9ter Alvaro Beige - Pure Alpaca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/","og_locale":"es_ES","og_type":"article","og_title":"Su\u00e9ter Alvaro Beige - Pure Alpaca","og_url":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/","og_site_name":"Pure Alpaca","article_publisher":"https:\/\/www.facebook.com\/purealpacaofficial","article_modified_time":"2026-05-04T13:12:29+00:00","og_image":[{"width":1004,"height":1504,"url":"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2025\/04\/Chompa-Alvarao_Beige_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/","url":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/","name":"Su\u00e9ter Alvaro Beige - Pure Alpaca","isPartOf":{"@id":"https:\/\/purealpacastores.com\/peru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/#primaryimage"},"image":{"@id":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/#primaryimage"},"thumbnailUrl":"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2025\/04\/Chompa-Alvarao_Beige_1.jpg","datePublished":"2025-03-09T02:22:01+00:00","dateModified":"2026-05-04T13:12:29+00:00","breadcrumb":{"@id":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/#primaryimage","url":"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2025\/04\/Chompa-Alvarao_Beige_1.jpg","contentUrl":"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2025\/04\/Chompa-Alvarao_Beige_1.jpg","width":1004,"height":1504},{"@type":"BreadcrumbList","@id":"https:\/\/purealpacastores.com\/peru\/producto\/chompa-alvaro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/purealpacastores.com\/peru\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/purealpacastores.com\/peru\/tienda\/"},{"@type":"ListItem","position":3,"name":"Su\u00e9ter Alvaro Beige"}]},{"@type":"WebSite","@id":"https:\/\/purealpacastores.com\/peru\/#website","url":"https:\/\/purealpacastores.com\/peru\/","name":"Pure Alpaca","description":"Boutique de Prendas de Alpaca","publisher":{"@id":"https:\/\/purealpacastores.com\/peru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/purealpacastores.com\/peru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/purealpacastores.com\/peru\/#organization","name":"Pure Alpaca","url":"https:\/\/purealpacastores.com\/peru\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/purealpacastores.com\/peru\/#\/schema\/logo\/image\/","url":"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2021\/04\/logo-2da-version-1.png","contentUrl":"https:\/\/purealpacastores.com\/peru\/wp-content\/uploads\/2021\/04\/logo-2da-version-1.png","width":300,"height":200,"caption":"Pure Alpaca"},"image":{"@id":"https:\/\/purealpacastores.com\/peru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/purealpacaofficial","https:\/\/www.youtube.com\/channel\/UCGZZKwsBB5LtQ_jlpO0AdHA"]}]}},"_links":{"self":[{"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/product\/25219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/comments?post=25219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/media\/26060"}],"wp:attachment":[{"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/media?parent=25219"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/product_brand?post=25219"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/product_cat?post=25219"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/purealpacastores.com\/peru\/wp-json\/wp\/v2\/product_tag?post=25219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}